{"id":4095,"count":7,"description":"","link":"http:\/\/archiwum.radiopodlasie.pl\/NEW\/tag\/gen-anders\/","name":"gen. Anders","slug":"gen-anders","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/archiwum.radiopodlasie.pl\/NEW\/wp-json\/wp\/v2\/tags\/4095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/archiwum.radiopodlasie.pl\/NEW\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/archiwum.radiopodlasie.pl\/NEW\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/archiwum.radiopodlasie.pl\/NEW\/wp-json\/wp\/v2\/posts?tags=4095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}